{"id":5012,"count":1,"description":"","link":"https:\/\/golossokal.com.ua\/en\/tag\/likarnia-unbroken","name":"\u043b\u0456\u043a\u0430\u0440\u043d\u044f UNBROKEN","slug":"likarnia-unbroken","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u043b\u0456\u043a\u0430\u0440\u043d\u044f UNBROKEN \u0410\u0440\u0445\u0456\u0432\u0438 - Sokal Voice - news about Sokal, Sheptytskyi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u043b\u0456\u043a\u0430\u0440\u043d\u044f UNBROKEN \u0410\u0440\u0445\u0456\u0432\u0438 - Sokal Voice - news about Sokal, Sheptytskyi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/golossokal.com.ua\/tag\/likarnia-unbroken\" \/>\n<meta property=\"og:site_name\" content=\"Sokal Voice - news about Sokal, Sheptytskyi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/golossokal.com.ua\\\/tag\\\/likarnia-unbroken\",\"url\":\"https:\\\/\\\/golossokal.com.ua\\\/tag\\\/likarnia-unbroken\",\"name\":\"\u043b\u0456\u043a\u0430\u0440\u043d\u044f UNBROKEN \u0410\u0440\u0445\u0456\u0432\u0438 - Sokal Voice - news about Sokal, Sheptytskyi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/golossokal.com.ua\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/golossokal.com.ua\\\/tag\\\/likarnia-unbroken#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/golossokal.com.ua\\\/tag\\\/likarnia-unbroken#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043e\u043b\u043e\u0432\u043d\u0430\",\"item\":\"https:\\\/\\\/golossokal.com.ua\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u043b\u0456\u043a\u0430\u0440\u043d\u044f UNBROKEN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/golossokal.com.ua\\\/#website\",\"url\":\"https:\\\/\\\/golossokal.com.ua\\\/\",\"name\":\"\u0413\u043e\u043b\u043e\u0441 \u0421\u043e\u043a\u0430\u043b\u044c\u0449\u0438\u043d\u0438 | Sokal Voice\",\"description\":\"News of Western Ukraine\",\"publisher\":{\"@id\":\"https:\\\/\\\/golossokal.com.ua\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/golossokal.com.ua\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/golossokal.com.ua\\\/#organization\",\"name\":\"\u0413\u043e\u043b\u043e\u0441 \u0421\u043e\u043a\u0430\u043b\u044c\u0449\u0438\u043d\u0438 | Sokal Voice\",\"url\":\"https:\\\/\\\/golossokal.com.ua\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/golossokal.com.ua\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/golossokal.com.ua\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-web.png\",\"contentUrl\":\"https:\\\/\\\/golossokal.com.ua\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-web.png\",\"width\":200,\"height\":80,\"caption\":\"\u0413\u043e\u043b\u043e\u0441 \u0421\u043e\u043a\u0430\u043b\u044c\u0449\u0438\u043d\u0438 | Sokal Voice\"},\"image\":{\"@id\":\"https:\\\/\\\/golossokal.com.ua\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/golossokal\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@golos.sokal\",\"https:\\\/\\\/t.me\\\/golososokal\",\"https:\\\/\\\/www.instagram.com\\\/sokalvoice\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u043b\u0456\u043a\u0430\u0440\u043d\u044f UNBROKEN \u0410\u0440\u0445\u0456\u0432\u0438 - Sokal Voice - news about Sokal, Sheptytskyi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"\u043b\u0456\u043a\u0430\u0440\u043d\u044f UNBROKEN \u0410\u0440\u0445\u0456\u0432\u0438 - Sokal Voice - news about Sokal, Sheptytskyi","og_url":"https:\/\/golossokal.com.ua\/tag\/likarnia-unbroken","og_site_name":"Sokal Voice - news about Sokal, Sheptytskyi","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/golossokal.com.ua\/tag\/likarnia-unbroken","url":"https:\/\/golossokal.com.ua\/tag\/likarnia-unbroken","name":"\u043b\u0456\u043a\u0430\u0440\u043d\u044f UNBROKEN \u0410\u0440\u0445\u0456\u0432\u0438 - Sokal Voice - news about Sokal, Sheptytskyi","isPartOf":{"@id":"https:\/\/golossokal.com.ua\/#website"},"breadcrumb":{"@id":"https:\/\/golossokal.com.ua\/tag\/likarnia-unbroken#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/golossokal.com.ua\/tag\/likarnia-unbroken#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043e\u043b\u043e\u0432\u043d\u0430","item":"https:\/\/golossokal.com.ua\/"},{"@type":"ListItem","position":2,"name":"\u043b\u0456\u043a\u0430\u0440\u043d\u044f UNBROKEN"}]},{"@type":"WebSite","@id":"https:\/\/golossokal.com.ua\/#website","url":"https:\/\/golossokal.com.ua\/","name":"\u0413\u043e\u043b\u043e\u0441 \u0421\u043e\u043a\u0430\u043b\u044c\u0449\u0438\u043d\u0438 | Sokal Voice","description":"News of Western Ukraine","publisher":{"@id":"https:\/\/golossokal.com.ua\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/golossokal.com.ua\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/golossokal.com.ua\/#organization","name":"\u0413\u043e\u043b\u043e\u0441 \u0421\u043e\u043a\u0430\u043b\u044c\u0449\u0438\u043d\u0438 | Sokal Voice","url":"https:\/\/golossokal.com.ua\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/golossokal.com.ua\/#\/schema\/logo\/image\/","url":"https:\/\/golossokal.com.ua\/wp-content\/uploads\/2025\/12\/logo-web.png","contentUrl":"https:\/\/golossokal.com.ua\/wp-content\/uploads\/2025\/12\/logo-web.png","width":200,"height":80,"caption":"\u0413\u043e\u043b\u043e\u0441 \u0421\u043e\u043a\u0430\u043b\u044c\u0449\u0438\u043d\u0438 | Sokal Voice"},"image":{"@id":"https:\/\/golossokal.com.ua\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/golossokal\/","https:\/\/www.tiktok.com\/@golos.sokal","https:\/\/t.me\/golososokal","https:\/\/www.instagram.com\/sokalvoice"]}]}},"_links":{"self":[{"href":"https:\/\/golossokal.com.ua\/en\/wp-json\/wp\/v2\/tags\/5012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golossokal.com.ua\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/golossokal.com.ua\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/golossokal.com.ua\/en\/wp-json\/wp\/v2\/posts?tags=5012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}